{"id":3978,"date":"2024-05-22T12:17:12","date_gmt":"2024-05-22T12:17:12","guid":{"rendered":"https:\/\/powderblue-hamster-289484.hostingersite.com\/?p=3978"},"modified":"2024-11-28T12:45:20","modified_gmt":"2024-11-28T12:45:20","slug":"as-novas-30-medidas-do-governo-para-responder-a-crise-na-habitacao","status":"publish","type":"post","link":"https:\/\/extravalue.pt\/en\/as-novas-30-medidas-do-governo-para-responder-a-crise-na-habitacao\/","title":{"rendered":"The Government's 30 New Measures to Address the Housing Crisis"},"content":{"rendered":"<p>The Ministry of Infrastructure and Housing proposes 30 new measures aimed at reversing some of the measures proposed and approved in the 'More Housing' package from the previous year.<\/p>\n<p><!--more--><\/p>\n<h4><b>As 30 novas medidas para a Habita\u00e7\u00e3o:<\/b><\/h4>\n<ol>\n<li>Disponibiliza\u00e7\u00e3o de Im\u00f3veis P\u00fablicos para Habita\u00e7\u00e3o (build to rent) com renda\/pre\u00e7o acess\u00edvel\u00a0(90 dias)<\/li>\n<li>Regime legal semi-autom\u00e1tico de aproveitamento de im\u00f3veis p\u00fablicos devolutos ou sub-utilizados por apresenta\u00e7\u00e3o casu\u00edstica de projeto de Habita\u00e7\u00e3o\u00a0(10 dias)<\/li>\n<li>Altera\u00e7\u00e3o da Lei dos Solos para permitir o uso de solos r\u00fasticos para solu\u00e7\u00f5es sustent\u00e1veis de Habita\u00e7\u00e3o:\n<ol>\n<li>Habita\u00e7\u00e3o a Custos Controlados;<\/li>\n<li>Arrendamento acess\u00edvel;<\/li>\n<li>Alojamento tempor\u00e1rio (refor\u00e7o BNAUT);<\/li>\n<li>Oferta para casas de fun\u00e7\u00e3o: professores, for\u00e7as de seguran\u00e7a, trabalhadores agr\u00edcolas, industriais e setor do turismo<\/li>\n<\/ol>\n<\/li>\n<li>Cria\u00e7\u00e3o de B\u00f3nus Construtivo (aumento dos \u00edndices e limites de densidade urban\u00edstica)\u00a0(90 dias)<\/li>\n<li>Novas Centralidades Urbanas na envolvente das zonas de press\u00e3o urban\u00edstica, com planos urban\u00edsticos sustent\u00e1veis (estudo 120 dias)<\/li>\n<li>Garantia do Estado a cr\u00e9dito para constru\u00e7\u00e3o de cooperativas com entrega de terreno p\u00fablico\u00a0(90 dias)<\/li>\n<li>Linhas de cr\u00e9dito para promo\u00e7\u00e3o do build to rent\u00a0(60 dias)<\/li>\n<li>Pacto com Agentes do Sector para aumento da capacidade construtiva \u2013 estabilidade da capacidade produtiva, industrializa\u00e7\u00e3o do processo, atra\u00e7\u00e3o e qualifica\u00e7\u00e3o de m\u00e3o-de-obra residente<\/li>\n<li>Redu\u00e7\u00e3o de IVA para a taxa m\u00ednima de 6% para as obras de reabilita\u00e7\u00e3o e constru\u00e7\u00e3o de Habita\u00e7\u00e3o, com limites em fun\u00e7\u00e3o dos pre\u00e7os (at\u00e9 ao fim da legislatura)<\/li>\n<li>Desbloqueio de 25.000 casas do PRR com ado\u00e7\u00e3o de termo de responsabilidade das C\u00e2maras Municipais, de modo a acelerar os processos\u00a0(10 dias)<\/li>\n<li>Refor\u00e7o de financiamento para viabilizar o desenvolvimento de milhares de outros fogos candidatos, mas n\u00e3o financiados no PRR\u00a0(30 dias)<\/li>\n<li>Robustecer a capacidade de promo\u00e7\u00e3o do IHRU atrav\u00e9s da Constru\u00e7\u00e3o P\u00fablica EPE, na realiza\u00e7\u00e3o dos fogos do Programa de Arrendamento Acess\u00edvel<\/li>\n<li>Revoga\u00e7\u00e3o do arrendamento for\u00e7ado<\/li>\n<li>Revoga\u00e7\u00e3o da medida do Mais Habita\u00e7\u00e3o de garantia e substitui\u00e7\u00e3o do Estado como arrendat\u00e1rio<\/li>\n<li>Corre\u00e7\u00e3o das distor\u00e7\u00f5es introduzidas ao Regime de Arrendamento Urbano nos \u00faltimos 8 anos (nomear grupo de trabalho)<\/li>\n<li>Cria\u00e7\u00e3o do contrato de investimento para built to rent e available-to-let<\/li>\n<li>Possibilitar constituir um ou mais contratos de seguro atrav\u00e9s de um prestador que n\u00e3o seja o da prefer\u00eancia do mutuante<\/li>\n<li>Regulamenta\u00e7\u00e3o, aprofundamento e aperfei\u00e7oamento da legisla\u00e7\u00e3o de desburocratiza\u00e7\u00e3o e simplifica\u00e7\u00e3o administrativa urban\u00edstica<\/li>\n<li>Aprovar o C\u00f3digo da Constru\u00e7\u00e3o<\/li>\n<li>Implementa\u00e7\u00e3o da utiliza\u00e7\u00e3o metodologia BIM e aproxima\u00e7\u00e3o de plataformas municipais de licenciamento de interface com os agentes econ\u00f3micos<\/li>\n<li>Adequar o conceito de custos controlados e renda acess\u00edvel para refletir o segmento de habita\u00e7\u00e3o acess\u00edvel em cada local\/momento. Gerando maior previsibilidade e perenidade ao mercado<\/li>\n<li>Alojamento Local, revoga\u00e7\u00e3o da CEAL1, da caducidade da licen\u00e7a e transmissibilidade, e da altera\u00e7\u00e3o ao coeficiente de vetustez<\/li>\n<li>Cria\u00e7\u00e3o do Portal do IHRU para acompanhamento dos processos de candidaturas<\/li>\n<li>Garantia P\u00fablica aos jovens para viabilizar o financiamento banc\u00e1rio (15 dias)<\/li>\n<li>Isen\u00e7\u00e3o IMT e IS jovem: isen\u00e7\u00e3o dos jovens at\u00e9 aos 35 anos nos im\u00f3veis at\u00e9 ao 4\u00ba escal\u00e3o (at\u00e9 316 mil euros)<\/li>\n<li>Reformula\u00e7\u00e3o do Porta 65: para colocar a realidade econ\u00f3mica do jovem em primeiro lugar, acabando com exclus\u00f5es em fun\u00e7\u00e3o de limites de rendas<\/li>\n<li>Programa de Emerg\u00eancia para o Alojamento Estudantil<\/li>\n<li>Implementa\u00e7\u00e3o do Plano Nacional Alojamento 2025-26: oferta de mais 18.000 camas\u00a0(30 dias)<\/li>\n<li>Agiliza\u00e7\u00e3o dos programas de subs\u00eddio de renda, eliminando as restri\u00e7\u00f5es, designadamente nas caducidades<\/li>\n<li>Cria\u00e7\u00e3o de regulamento de transi\u00e7\u00e3o entre as rendas apoiadas e renda acess\u00edvel, por forma a garantir a n\u00e3o exist\u00eancia de descontinuidades nos apoios<\/li>\n<\/ol>\n<p>Fonte: CNN Portugal<\/p>","protected":false},"excerpt":{"rendered":"<p>The Ministry of Infrastructure and Housing proposes 30 new measures aimed at reversing some of the measures proposed and approved in the 'More Housing' package from the previous year.<\/p>","protected":false},"author":1,"featured_media":2457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-habitacao"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/posts\/3978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/comments?post=3978"}],"version-history":[{"count":2,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/posts\/3978\/revisions"}],"predecessor-version":[{"id":4615,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/posts\/3978\/revisions\/4615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/media\/2457"}],"wp:attachment":[{"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/media?parent=3978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/categories?post=3978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extravalue.pt\/en\/wp-json\/wp\/v2\/tags?post=3978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}